{"id":2970,"date":"2024-03-01T11:07:41","date_gmt":"2024-03-01T10:07:41","guid":{"rendered":"https:\/\/hank.brussels\/nos-ingredients-et-materiaux\/"},"modified":"2025-02-25T15:34:41","modified_gmt":"2025-02-25T14:34:41","slug":"nos-ingredients-et-materiaux","status":"publish","type":"page","link":"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/","title":{"rendered":"Nos ingr\u00e9dients et mat\u00e9riaux"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2970\" class=\"elementor elementor-2970 elementor-2\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ec4ad0a e-flex e-con-boxed e-con e-parent\" data-id=\"ec4ad0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-747b8b6 elementor-widget elementor-widget-et_menu_list\" data-id=\"747b8b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"et_menu_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        \n        <ul class=\"et-menu-list  menu-list-9857 text-left\">\n    \n            <li class=\"menu-item menu-item-object-page menu-item-has-children menu-parent-item menu-item-776\">\n\n    \t    \n        \t        \t\t<div class=\"menu-sublist\"><ul>\n            <li class=\"menu-item  menu-item-3739\">\n\n            \n                <div class=\"subitem-title-holder    elementor-repeater-item-f9769cb\">\n\n                    <a class=\"menu-title et-column-title  \" href=\"https:\/\/hank.brussels\/fr\/hank-deco-savon-bruxelles\/\" target=\"_self\" title=\"\u00c0 propos de Hank\" > \n\n                    <h2>\u00c0 propos de Hank<\/h2>\n                    <\/a>\n\n                <\/div> \n            \n            <\/li>\n\n        \n            <li class=\"menu-item  menu-item-7605\">\n\n            \n                <div class=\"subitem-title-holder    elementor-repeater-item-4416650\">\n\n                    <a class=\"menu-title et-column-title  \" href=\"https:\/\/hank.brussels\/fr\/lengagement-ecologique-de-hank\/\" target=\"_self\" title=\"\u00c9thique et durabilit\u00e9\" > \n\n                    <h3>\u00c9thique et durabilit\u00e9<\/h3>\n                    <\/a>\n\n                <\/div> \n            \n            <\/li>\n\n        \n            <li class=\"menu-item current-menu-item menu-item-6346\">\n\n            \n                <div class=\"subitem-title-holder    elementor-repeater-item-dae42ac\">\n\n                    <a class=\"menu-title et-column-title  \" href=\"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/\" target=\"_self\" title=\"Ingr\u00e9dients &amp; Mat\u00e9riaux\" > \n\n                    <h3>Ingr\u00e9dients &amp; Mat\u00e9riaux<\/h3>\n                    <\/a>\n\n                <\/div> \n            \n            <\/li>\n\n        <\/ul><\/div>\n        \t\n            <\/li>\n\n        <\/ul>\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-42e7592 e-flex e-con-boxed e-con e-parent\" data-id=\"42e7592\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c45e9e elementor-widget elementor-widget-etheme_animated_headline\" data-id=\"2c45e9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;shape&quot;:&quot;curly&quot;,&quot;text_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;duration&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"etheme_animated_headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        \n        <div class=\"etheme-headline-wrapper\">\n            <h1 class=\"etheme-headline\" data-style=\"highlight\">\n\t\t                        <span class=\"etheme-headline-text-wrapper\">\n                \n\t\t        Nos ingr\u00e9dients<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 500 150\" preserveAspectRatio=\"none\"><path d=\"M5 146.575C5 146.575 44.2779 116.935 75.4221 117.006C106.397 117.078 114.378 146.794 145.352 146.575C175.818 146.36 193.202 117.497 223.663 117.006C255.312 116.496 254.05 146.789 285.704 146.575C316.847 146.365 334.84 117.006 365.985 117.006C397.129 117.006 395.406 146.867 426.548 146.575C457.013 146.29 495 117.006 495 117.006\"><\/path><\/svg>                \n                <\/span>\n                            <\/h1>\n        <\/div>\n        \n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-907790c elementor-widget elementor-widget-heading\" data-id=\"907790c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Huiles et Beurres<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-021a5f1 elementor-widget elementor-widget-text-editor\" data-id=\"021a5f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default elementor-inline-editing pen\" contenteditable=\"true\" data-elementor-setting-key=\"title\" data-pen-placeholder=\"Type Here...\">Nous utilisons majoritairement des huiles biologiques et \u00e9thiques. Certaines huiles ne sont pas locales, car il est purement impossible d&rsquo;avoir toutes les huiles et beurres cultiv\u00e9s en Belgique, cela va de soi, et nous sommes donc parfois oblig\u00e9s de nous approvisionner \u00e0 l&rsquo;\u00e9tranger, mais nous veillons \u00e0 garantir la tra\u00e7abilit\u00e9 des diff\u00e9rents ingr\u00e9dients.<\/h4>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4210b79 elementor-widget elementor-widget-n-accordion\" data-id=\"4210b79\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6920\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6920\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Huile d'olive (Extra Vierge) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6920\" class=\"elementor-element elementor-element-f62fcae e-flex e-con-boxed e-con e-child\" data-id=\"f62fcae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55a3a85 elementor-widget elementor-widget-text-editor\" data-id=\"55a3a85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/17404-olea-europaea-fruit-oil\">olea europea fruit oil<\/a><\/p>\n<p class=\"p1\">Utilis\u00e9e depuis plus de cinq mille ans par les \u00c9gyptiens, l&rsquo;huile d&rsquo;olive aux multiples vertus a \u00e9t\u00e9 utilis\u00e9e comme base pour la cr\u00e9ation du premier savon et m\u00eame utilis\u00e9e par les Grecs comme une huile stimulante pour les massages corporels.<\/p>\n<p class=\"p1\">Notre huile d&rsquo;olive d&rsquo;origine europ\u00e9enne (Espagne, Italie, France) est extra vierge et extraite par premi\u00e8re pression \u00e0 froid. Hydratante et antioxydante, elle maintient l&rsquo;hydratation de la peau et aide \u00e0 retarder les signes du vieillissement. Anti-inflammatoire et antibact\u00e9rienne, elle aide \u00e9galement \u00e0 la cicatrisation.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6921\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6921\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Huile de Coco (Press\u00e9e \u00e0 froid) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6921\" class=\"elementor-element elementor-element-6a0fd4d e-con-full e-flex e-con e-child\" data-id=\"6a0fd4d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6921\" class=\"elementor-element elementor-element-61e739a e-flex e-con-boxed e-con e-child\" data-id=\"61e739a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3432f8f elementor-widget elementor-widget-text-editor\" data-id=\"3432f8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/16747-cocos-nucifera-oil\">cocos nucifera oil<\/a><\/p>\n<p class=\"p1\">D\u00e9riv\u00e9e de la pulpe fra\u00eeche, l&rsquo;huile v\u00e9g\u00e9tale de noix de coco s\u00e9duit gr\u00e2ce \u00e0 son parfum exotique et ses nombreuses vertus cosm\u00e9tiques : elle nourrit, hydrate, r\u00e9pare, et est tr\u00e8s facilement absorb\u00e9e par la peau.<\/p>\n<p class=\"p1\">L&rsquo;huile de coco est compos\u00e9e d&rsquo;acides gras, principalement de l&rsquo;acide laurique, avec des quantit\u00e9s moindres d&rsquo;acides palmitique, caprylique et myristique. Dans la fabrication de savon, elle constitue un bon substitut \u00e0 l&rsquo;huile de palme et permet de produire, en combinaison avec d&rsquo;autres huiles, un savon avec une belle mousse cr\u00e9meuse. Les gousses des graines contenant l&rsquo;huile sont retir\u00e9es avant le processus d&rsquo;extraction \u00e0 froid.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6922\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6922\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Beurre de Karit\u00e9 (Ethique et Press\u00e9 \u00e0 la main) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6922\" class=\"elementor-element elementor-element-ee4c625 e-con-full e-flex e-con e-child\" data-id=\"ee4c625\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6922\" class=\"elementor-element elementor-element-a6db342 e-flex e-con-boxed e-con e-child\" data-id=\"a6db342\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ae7686 elementor-widget elementor-widget-text-editor\" data-id=\"1ae7686\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le beurre de karit\u00e9 est un secret de beaut\u00e9 pr\u00e9cieux des femmes africaines, utilis\u00e9 d\u00e8s le plus jeune \u00e2ge pour hydrater, prot\u00e9ger et nourrir la peau. Riche en vitamines A, D, E et F, il hydrate en profondeur, adoucit et apaise, ce qui en fait un ingr\u00e9dient essentiel dans nos savons. Au-del\u00e0 de ses remarquables bienfaits pour la peau, il conf\u00e8re \u00e0 nos produits une mousse dense et cr\u00e9meuse pour une exp\u00e9rience in\u00e9galable.  <\/p>\n<p>Issu des savanes bois\u00e9es d&rsquo;Afrique de l&rsquo;Ouest, le beurre de karit\u00e9 provient de l&rsquo;arbre \u00e0 karit\u00e9, une esp\u00e8ce \u00e0 croissance lente qui met environ 15 ans pour produire ses premiers fruits. Le fruit, ressemblant \u00e0 un petit avocat \u00e0 la pulpe sucr\u00e9e, contient une graine dont est extrait ce pr\u00e9cieux beurre. Chaque arbre ne produit que quelques kilogrammes de noix par an, faisant du beurre de karit\u00e9 une ressource rare et pr\u00e9cieuse.  <\/p>\n<p>Dans le village de Kongo, au nord du Ghana, o\u00f9 l\u2019\u00e9lectricit\u00e9 et l\u2019eau courante restent un luxe, la production de beurre de karit\u00e9 joue un r\u00f4le essentiel dans l&rsquo;\u00e9conomie locale et le travail \u00e9quitable des femmes. En travaillant ensemble, elles transforment le fruit de ces arbres sauvages en une source d\u2019autonomisation \u00e9conomique et d\u2019ind\u00e9pendance. Ce processus pr\u00e9serve les savoirs traditionnels tout en favorisant des moyens de subsistance durables dans une r\u00e9gion o\u00f9 les opportunit\u00e9s sont limit\u00e9es.  <\/p>\n<p>De plus, la production de beurre de karit\u00e9 est profond\u00e9ment ancr\u00e9e dans le respect de la nature et de l\u2019Ubuntu, cette croyance selon laquelle \u00ab Je suis parce que nous sommes \u00bb. Chaque \u00e9tape, de la r\u00e9colte \u00e0 la transformation, refl\u00e8te un \u00e9quilibre entre la tradition et la n\u00e9cessit\u00e9 de prendre soin des g\u00e9n\u00e9rations futures. En int\u00e9grant ce beurre de karit\u00e9 produit de mani\u00e8re durable dans nos savons, nous veillons \u00e0 ce que ses bienfaits aillent bien au-del\u00e0 du soin de la peau, en contribuant \u00e0 la pr\u00e9servation de la culture, de l\u2019environnement et des moyens de subsistance locaux.  <\/p>\n<p>Dans chaque <a href=\"https:\/\/hank.brussels\/fr\/nos-savons\/\">barre de savon Hank<\/a>, cet ingr\u00e9dient d\u2019exception raconte une histoire \u2013 une histoire de r\u00e9silience, de communaut\u00e9 et du lien ind\u00e9fectible entre l&rsquo;humain et la terre.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6923\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6923\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Huile d'amande douce (Press\u00e9e \u00e0 froid) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6923\" class=\"elementor-element elementor-element-c6daf0b e-con-full e-flex e-con e-child\" data-id=\"c6daf0b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6923\" class=\"elementor-element elementor-element-84373a6 e-flex e-con-boxed e-con e-child\" data-id=\"84373a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fe16a7 elementor-widget elementor-widget-text-editor\" data-id=\"1fe16a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/18533-prunus-amygdalus-dulcis-oil\">Prunus Amygdalus Dulcis oil<\/a><\/p>\n<p>L&rsquo;huile d&rsquo;amande douce hydrate et prot\u00e8ge la peau. Apaisante, elle soulage les irritations et les d\u00e9mangeaisons. Nourrissante, elle est parfaite en cas de peau gerc\u00e9e ou s\u00e8che, ainsi que en pr\u00e9vention des vergetures. Elle contient de la vitamine A, qui am\u00e9liore l&rsquo;\u00e9lasticit\u00e9 de la peau.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6924\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6924\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Huile de P\u00e9pins de Raisin (press\u00e9e \u00e0 froid) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6924\" class=\"elementor-element elementor-element-c37a7f6 e-con-full e-flex e-con e-child\" data-id=\"c37a7f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6924\" class=\"elementor-element elementor-element-abdca94 e-flex e-con-boxed e-con e-child\" data-id=\"abdca94\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c54bed elementor-widget elementor-widget-text-editor\" data-id=\"3c54bed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/10506-vitis-vinifera-seed-oil\">Vitis vinifera oil<\/a><\/p>\n<p>Les raisins sont l&rsquo;un des fruits les plus anciens et les plus cultiv\u00e9s. Si elle est utilis\u00e9e comme fruit de table ou pour produire du vin, la consommation d&rsquo;huile de p\u00e9pins de raisin est en revanche tr\u00e8s r\u00e9cente et doit son existence aux d\u00e9chets de vin. Particuli\u00e8rement l\u00e9g\u00e8re, l&rsquo;huile de p\u00e9pins de raisin p\u00e9n\u00e8tre facilement dans la peau. C&rsquo;est une huile riche en vitamine E, tr\u00e8s douce pour la peau, \u00e9molliente et hydratante.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6925\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6925\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Huile de Ricin (Press\u00e9e \u00e0 froid) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6925\" class=\"elementor-element elementor-element-e90d20c e-con-full e-flex e-con e-child\" data-id=\"e90d20c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6925\" class=\"elementor-element elementor-element-c112b09 e-flex e-con-boxed e-con e-child\" data-id=\"c112b09\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f84116d elementor-widget elementor-widget-text-editor\" data-id=\"f84116d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/4337-ricinus-communis-seed-oil\">Ricinus communis oil<\/a><\/p>\n<p class=\"p2\">\u00c0 partir des graines d&rsquo;un arbuste, l&rsquo;huile de ricin est principalement produite dans de nombreux pays chauds tels que l&rsquo;Inde, la Chine, le Br\u00e9sil ou l&rsquo;Afrique. En cosm\u00e9tique, l&rsquo;huile de ricin est utilis\u00e9e depuis au moins le 19\u00e8me si\u00e8cle pour ses multiples vertus pour la peau et les cheveux. Adoucissante, nourrissante, antibact\u00e9rienne et antifongique, cette huile \u00e0 la texture \u00e9paisse et visqueuse est riche en acides gras essentiels n\u00e9cessaires \u00e0 la sant\u00e9 de la peau. Elle convient \u00e0 tous les types de peau, m\u00eame les peaux grasses. Notre huile ne contient pas de ricine.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f7185b elementor-widget elementor-widget-heading\" data-id=\"5f7185b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Extraits de Plante &amp; Min\u00e9raux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01aa8c4 elementor-widget elementor-widget-n-accordion\" data-id=\"01aa8c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1740\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1740\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Charbon v\u00e9g\u00e9tal activ\u00e9 <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1740\" class=\"elementor-element elementor-element-8fb3a67 e-flex e-con-boxed e-con e-child\" data-id=\"8fb3a67\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44c1638 elementor-widget elementor-widget-text-editor\" data-id=\"44c1638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/2106-charcoal-powder\">Charcoal powder<\/a><\/p>\n<p>Le charbon actif est un ingr\u00e9dient naturel d\u00e9riv\u00e9 de la carbonisation de mati\u00e8res v\u00e9g\u00e9tales riches en carbone, utilis\u00e9 depuis l&rsquo;Antiquit\u00e9. Il est dot\u00e9 de propri\u00e9t\u00e9s purifiantes, exfoliantes et anti-pollution. <span style=\"font-family: inherit; font-size: inherit;\">C&rsquo;est un ingr\u00e9dient de choix pour les peaux grasses, ternes et fatigu\u00e9es. Gr\u00e2ce \u00e0 sa surface extr\u00eamement poreuse \u00e0 l&rsquo;\u00e9chelle microscopique, il retient les fluides tels que le s\u00e9bum et aide \u00e0 raviver le teint. <\/span><span style=\"font-family: inherit; font-size: inherit;\">C&rsquo;est \u00e9galement l&rsquo;ingr\u00e9dient cl\u00e9 de notre savon <a href=\"https:\/\/hank.brussels\/fr\/product\/beyond-the-pines-savon-au-charbon-vegetal-110g-purifiant-et-rafraichissant\/\"><span style=\"text-decoration: underline;\">Beyond the Pines<\/span><\/a>.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1741\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1741\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Banane (poudre) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1741\" class=\"elementor-element elementor-element-f5e8d5b e-con-full e-flex e-con e-child\" data-id=\"f5e8d5b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1741\" class=\"elementor-element elementor-element-ec8b4d2 e-flex e-con-boxed e-con e-child\" data-id=\"ec8b4d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc6ca89 elementor-widget elementor-widget-text-editor\" data-id=\"dc6ca89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/20144-musa-paradisiaca-banana-fruit-extract\">Musa Paradisiaca fruit<\/a><\/p>\n<p>L&rsquo;ingr\u00e9dient phare de notre <a href=\"https:\/\/hank.brussels\/fr\/product\/banana-savon-surgras-bio-110g-ideal-pour-les-peaux-seches\/\"><span style=\"text-decoration: underline;\">savon Banana<\/span><\/a> est bien plus qu&rsquo;un simple fruit d\u00e9licieux. D\u00e9j\u00e0 connue dans les rituels de beaut\u00e9 des \u00eeles, elle convient \u00e0 tous les types de peau et offre de nombreuses vertus. Riche en vitamines A, B, E, antioxydants, magn\u00e9sium et mangan\u00e8se, elle hydrate, prot\u00e8ge et maintient l&rsquo;\u00e9lasticit\u00e9 de la peau et aide \u00e0 lutter contre le vieillissement pr\u00e9matur\u00e9 de la peau. Et comme si cela ne suffisait pas, elle aide \u00e9galement \u00e0 \u00e9quilibrer les peaux grasses et probl\u00e9matiques. Un cocktail tr\u00e8s efficace pour une peau douce, souple et bien hydrat\u00e9e !<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1742\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1742\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Sel noir de Chypre <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1742\" class=\"elementor-element elementor-element-148df00 e-con-full e-flex e-con e-child\" data-id=\"148df00\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1742\" class=\"elementor-element elementor-element-8f5ee77 e-flex e-con-boxed e-con e-child\" data-id=\"8f5ee77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-840f4db elementor-widget elementor-widget-text-editor\" data-id=\"840f4db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le sel noir de Chypre, enrichi en charbon actif, est un ingr\u00e9dient aux propri\u00e9t\u00e9s purifiantes et d\u00e9toxifiantes puissantes. Utilis\u00e9 dans notre <span style=\"text-decoration: underline;\"><a href=\"https:\/\/hank.brussels\/fr\/product\/original-gangsta-savon-surgras-bio-110g-framboise-bleue-urbaine\/\">savon Original Gangsta<\/a><\/span>, ce sel volcanique est particuli\u00e8rement adapt\u00e9 aux peaux mixtes \u00e0 grasses, car il aide \u00e0 r\u00e9guler la production de s\u00e9bum tout en nettoyant les pores en profondeur. Ses cristaux exfoliants \u00e9liminent d\u00e9licatement les cellules mortes, r\u00e9v\u00e9lant un teint plus uniforme et une peau visiblement plus saine. Riche en min\u00e9raux, il nourrit la peau et pr\u00e9serve son \u00e9quilibre naturel. Le choix id\u00e9al pour une peau purifi\u00e9e, douce et revitalis\u00e9e.    <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1743\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1743\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Myrtilles (poudre) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1743\" class=\"elementor-element elementor-element-5690fdf e-con-full e-flex e-con e-child\" data-id=\"5690fdf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1743\" class=\"elementor-element elementor-element-5009483 e-flex e-con-boxed e-con e-child\" data-id=\"5009483\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15dbb67 elementor-widget elementor-widget-text-editor\" data-id=\"15dbb67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/8301-vaccinium-myrtillus-fruit-leaf-extract\">Vaccinium Myrtillus<\/a><\/p>\n<p>La myrtille est consid\u00e9r\u00e9e comme l&rsquo;un des superaliments les plus efficaces de la nature. Elle doit sa couleur \u00e0 un pigment et antioxydant appel\u00e9 anthocyanine. En cosm\u00e9tique, c&rsquo;est un agent anti-\u00e2ge puissant et renomm\u00e9 qui aide \u00e0 lutter contre les signes du vieillissement et \u00e0 r\u00e9duire les rougeurs de l&rsquo;\u00e9piderme. Les myrtilles stimulent \u00e9galement la microcirculation, rendant la peau plus \u00e9lastique, souple et ferme. Dans notre <a href=\"https:\/\/hank.brussels\/fr\/product\/wild-berries-savon-surgras-bio-110g\/\">savon Wild Berries<\/a>, il offre principalement un effet massant l\u00e9g\u00e8rement exfoliant et ajoute une touche de plaisir.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1744\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1744\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Calendula (extrait) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1744\" class=\"elementor-element elementor-element-f362698 e-con-full e-flex e-con e-child\" data-id=\"f362698\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1744\" class=\"elementor-element elementor-element-2f47f6a e-flex e-con-boxed e-con e-child\" data-id=\"2f47f6a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33f4e14 elementor-widget elementor-widget-text-editor\" data-id=\"33f4e14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: Calendula Officinalis<\/p>\n<p class=\"p1\">Le souci, \u00e9galement appel\u00e9 souci des jardins, est une fleur qui \u00e9tait d\u00e9j\u00e0 utilis\u00e9e en cuisine, en m\u00e9decine et en cosm\u00e9tique par les civilisations indienne, arabe et grecque de l&rsquo;Antiquit\u00e9, pour teindre les textiles ou comme plante aux propri\u00e9t\u00e9s m\u00e9dicinales. Il est cultiv\u00e9 en Europe depuis le XIIe si\u00e8cle, et ses propri\u00e9t\u00e9s th\u00e9rapeutiques sont connues depuis longtemps. Hildegarde de Bingen, une religieuse b\u00e9n\u00e9dictine, l&rsquo;utilisait contre la teigne. \u00c0 la m\u00eame \u00e9poque, Albert Le Grand recommandait son utilisation comme agent cicatrisant pour les piq\u00fbres d&rsquo;insectes et de serpents. Que ce soit par voie orale ou locale, le souci offre des propri\u00e9t\u00e9s th\u00e9rapeutiques tr\u00e8s diverses. On le trouve fr\u00e9quemment dans les soins dermatologiques, pour les b\u00e9b\u00e9s, pour les peaux sensibles et atopiques.<\/p>\n<p class=\"p1\">La Commission E, l&rsquo;ESCOP et l&rsquo;Organisation mondiale de la sant\u00e9 (OMS) reconnaissent les utilisations internes et externes du souci pour traiter les inflammations de la muqueuse de la bouche et de la gorge, ainsi que pour gu\u00e9rir les l\u00e9sions cutan\u00e9es (plaies, br\u00fblures, ecchymoses, etc.) et les ulc\u00e8res variqueux.<\/p>\n<p class=\"p1\">Nous l&rsquo;utilisons sous deux formes dans notre <span style=\"text-decoration: underline;\">savon Banana<\/span> : sous forme d&rsquo;extrait CO2 hautement concentr\u00e9 et sous forme de p\u00e9tales s\u00e9ch\u00e9s. Nos p\u00e9tales proviennent de soucis biologiques cultiv\u00e9s dans des jardins belges.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1745\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1745\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Jus de Carotte (fra\u00eechement press\u00e9) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1745\" class=\"elementor-element elementor-element-5ef3a08 e-con-full e-flex e-con e-child\" data-id=\"5ef3a08\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1745\" class=\"elementor-element elementor-element-7ded07d e-flex e-con-boxed e-con e-child\" data-id=\"7ded07d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1403b8 elementor-widget elementor-widget-text-editor\" data-id=\"e1403b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/37593-daucus-carota-sativa-root-juice\">Daucus Carota Sativa Root Juice<\/a><\/p>\n<p class=\"p1\">Nous le connaissons dans nos assiettes ou en jus, un peu moins en cosm\u00e9tique, du moins par le grand public. Le temps et la r\u00e9gion (ou les r\u00e9gions) d&rsquo;origine de la carotte cultiv\u00e9e ne sont pas clairement identifi\u00e9s et elle se retrouve partout. C&rsquo;est le l\u00e9gume le plus cultiv\u00e9 au monde, \u00e0 tel point que l&rsquo;on a l&rsquo;impression de le conna\u00eetre depuis la nuit des temps. Pourtant, il n&rsquo;\u00e9tait pas toujours orange, car cette couleur n&rsquo;aurait \u00e9merg\u00e9 qu&rsquo;\u00e0 la suite de s\u00e9lections au cours de la Renaissance, au 17\u00e8me si\u00e8cle. \u00c0 l&rsquo;origine, elles \u00e9taient principalement jaunes, pourpres ou blanches.<\/p>\n<p class=\"p1\">En cosm\u00e9tique, elle est principalement utilis\u00e9e pour son effet bonne mine et auto-bronzant gr\u00e2ce aux b\u00eata-carot\u00e8nes qu&rsquo;elle contient. Nourrissante et \u00e9molliente, elle aide \u00e0 hydrater la peau, en plus d&rsquo;\u00eatre adoucissante et assouplissante. C&rsquo;est un l\u00e9gume-racine qui convient \u00e0 tous les types de peau. Le jus de carotte donne une belle couleur jaune \u00e0 <a href=\"https:\/\/hank.brussels\/fr\/product\/banana-savon-surgras-bio-110g-ideal-pour-les-peaux-seches\/\"><span style=\"text-decoration: underline;\">nos savons Banana<\/span><\/a>, naturellement. Sa couleur s&rsquo;estompera progressivement avec le temps.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1746\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1746\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cranberries (poudre) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1746\" class=\"elementor-element elementor-element-95df3bd e-con-full e-flex e-con e-child\" data-id=\"95df3bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1746\" class=\"elementor-element elementor-element-ef0035d e-flex e-con-boxed e-con e-child\" data-id=\"ef0035d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e6242a elementor-widget elementor-widget-text-editor\" data-id=\"5e6242a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/15534-vaccinium-macrocarpon-fruit\">Vaccinium Macrocarpon<\/a><\/p>\n<p>La canneberge, appel\u00e9e \u00e9galement cranberry ou airelle en fran\u00e7ais, est une baie rouge issue d&rsquo;une petite plante vivace qui pousse dans les tourbi\u00e8res acides des pays du nord et des r\u00e9gions au climat froid comme le Canada, l&rsquo;Europe de l&rsquo;Est et du Nord. Ces superfruits sont riches en vitamine E et en flavono\u00efdes, des polyph\u00e9nols reconnus pour leur capacit\u00e9 \u00e0 combattre le stress oxydatif. Dans notre <a href=\"https:\/\/hank.brussels\/fr\/product\/wild-berries-savon-surgras-bio-110g\/\">savon Wild Berries<\/a>, il offre principalement un effet massant l\u00e9g\u00e8rement exfoliant et ajoute une touche de plaisir.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1747\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"8\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1747\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Sel de la mer Morte <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1747\" class=\"elementor-element elementor-element-7c41a45 e-con-full e-flex e-con e-child\" data-id=\"7c41a45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1747\" class=\"elementor-element elementor-element-c2bb529 e-flex e-con-boxed e-con e-child\" data-id=\"c2bb529\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cffcab7 elementor-widget elementor-widget-text-editor\" data-id=\"cffcab7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le sel de la mer Morte est r\u00e9put\u00e9 pour ses bienfaits th\u00e9rapeutiques gr\u00e2ce \u00e0 sa richesse exceptionnelle en min\u00e9raux essentiels tels que le magn\u00e9sium, le potassium, le calcium et le zinc. Ces \u00e9l\u00e9ments contribuent \u00e0 r\u00e9hydrater la peau, am\u00e9liorer son \u00e9lasticit\u00e9 et apaiser les inflammations. Il agit \u00e9galement comme un exfoliant naturel, \u00e9liminant les cellules mortes pour r\u00e9v\u00e9ler une peau rafra\u00eechie et \u00e9clatante. Id\u00e9al pour les peaux s\u00e8ches ou sensibles, ce sel favorise une meilleure circulation et aide \u00e0 soulager des probl\u00e8mes cutan\u00e9s tels que l\u2019ecz\u00e9ma ou le psoriasis. Le sel de la mer Morte est l\u2019ingr\u00e9dient principal de notre <span style=\"text-decoration: underline;\"><a href=\"https:\/\/hank.brussels\/fr\/product\/son-of-a-beach-savon-surgras-bio-110g-parfum-frais-de-mojito-enrichi-en-sel-de-la-mer-morte\/\">savon Son of a Beach <\/a><\/span>!    <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1748\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"9\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1748\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Argile Kaolin <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1748\" class=\"elementor-element elementor-element-5f0beab e-con-full e-flex e-con e-child\" data-id=\"5f0beab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1748\" class=\"elementor-element elementor-element-525569f e-flex e-con-boxed e-con e-child\" data-id=\"525569f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91df820 elementor-widget elementor-widget-text-editor\" data-id=\"91df820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019argile kaolin, reconnue pour sa texture fine et ses propri\u00e9t\u00e9s douces, est une pr\u00e9cieuse alli\u00e9e pour les peaux sensibles ou irrit\u00e9es. Naturellement riche en silice, elle agit comme un purifiant d\u00e9licat, absorbant les impuret\u00e9s et l\u2019exc\u00e8s de s\u00e9bum sans dess\u00e9cher la peau. Ses propri\u00e9t\u00e9s apaisantes aident \u00e0 calmer les rougeurs, les irritations et favorisent la r\u00e9g\u00e9n\u00e9ration d\u2019une peau saine. Int\u00e9gr\u00e9e dans notre <u><a href=\"https:\/\/hank.brussels\/fr\/product\/son-of-a-beach-savon-surgras-bio-110g-parfum-frais-de-mojito-enrichi-en-sel-de-la-mer-morte\/\">savon Son of a Beach<\/a><\/u>, elle apporte un effet velout\u00e9, laissant la peau plus lisse, plus douce et plus \u00e9clatante.   <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1749\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"10\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1749\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Th\u00e9 matcha (poudre) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1749\" class=\"elementor-element elementor-element-42a8347 e-con-full e-flex e-con e-child\" data-id=\"42a8347\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1749\" class=\"elementor-element elementor-element-727ab8d e-flex e-con-boxed e-con e-child\" data-id=\"727ab8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72d2080 elementor-widget elementor-widget-text-editor\" data-id=\"72d2080\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>INCI: <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/30546-camellia-sinensis-leaf-powder\">Camellia Sinensis<\/a> <\/p>\n<p>Le matcha, qui signifie \u00ab th\u00e9 broy\u00e9 \u00bb en japonais, est un superaliment d\u00e9j\u00e0 bien connu comme boisson chaude ou froide. Mais c&rsquo;est aussi un ingr\u00e9dient actif tr\u00e8s efficace pour la peau, plus concentr\u00e9 que son cousin, le th\u00e9 vert classique ! Provenant du Camellia sinensis, sa technique de r\u00e9colte est tr\u00e8s diff\u00e9rente de celle du th\u00e9 vert classique : les arbustes de th\u00e9 sont priv\u00e9s de soleil pendant environ un mois avant la r\u00e9colte. La photosynth\u00e8se est r\u00e9duite et l&rsquo;arbuste produit plus de chlorophylles et d&rsquo;acides amin\u00e9s pour compenser le manque de lumi\u00e8re. Une fois r\u00e9colt\u00e9, il est s\u00e9ch\u00e9 \u00e0 l&rsquo;air libre, puis r\u00e9duit en une pr\u00e9cieuse poudre fine.<\/p>\n<p>C&rsquo;est le secret de sa couleur vive. Gr\u00e2ce \u00e0 ce processus, le matcha est hautement concentr\u00e9 en vitamines A, E et cat\u00e9chines, de puissants antioxydants avec une action apaisante et anti-inflammatoire, ce qui en fait un ingr\u00e9dient de choix pour lutter contre le vieillissement pr\u00e9matur\u00e9 de la peau, ainsi que pour bien d&rsquo;autres usages. Connue pour les peaux \u00e0 probl\u00e8mes pour son pouvoir purifiant et astringent.<\/p>\n<p>Nous devions en faire tout un savon ! Nous avons donc cr\u00e9\u00e9 le <a href=\"https:\/\/hank.brussels\/fr\/product\/savon-surgras-bio-matcha-mint-110g-rafraichissant-et-detoxifiant\/\"><span style=\"text-decoration: underline;\">savon Matcha Mint<\/span><\/a>, pour les aficionados de th\u00e9 et de zen comme nous !<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-17410\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"11\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-17410\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Paprika (poudre) <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-17410\" class=\"elementor-element elementor-element-af71c7d e-con-full e-flex e-con e-child\" data-id=\"af71c7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-17410\" class=\"elementor-element elementor-element-38fa7b9 e-flex e-con-boxed e-con e-child\" data-id=\"38fa7b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2502909 elementor-widget elementor-widget-text-editor\" data-id=\"2502909\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La poudre de paprika, obtenue \u00e0 partir de poivrons rouges s\u00e9ch\u00e9s et finement moulus, est un v\u00e9ritable atout naturel pour la peau. Riche en antioxydants comme la vitamine C et les carot\u00e9no\u00efdes, elle lutte contre les radicaux libres, stimule la production de collag\u00e8ne et illumine le teint. Ses propri\u00e9t\u00e9s stimulantes am\u00e9liorent la circulation, revitalisant ainsi les peaux ternes ou fatigu\u00e9es. Naturellement anti-inflammatoire et antibact\u00e9rienne, elle apaise les imperfections et contribue \u00e0 maintenir un teint net. Int\u00e9gr\u00e9e dans nos savons, elle sublime l\u2019\u00e9clat de la peau tout en offrant une teinte chaude et naturelle \u00e0 <span style=\"text-decoration: underline;\"><a href=\"https:\/\/hank.brussels\/fr\/product\/original-gangsta-savon-surgras-bio-110g-framboise-bleue-urbaine\/\">notre savon Original Gangsta<\/a><\/span>.    <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d725c7c elementor-widget elementor-widget-heading\" data-id=\"d725c7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Autres<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-493387b e-flex e-con-boxed e-con e-parent\" data-id=\"493387b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e84c7f elementor-widget elementor-widget-n-accordion\" data-id=\"3e84c7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6550\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6550\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Fragrance <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6550\" class=\"elementor-element elementor-element-bb0b3e3 e-con-full e-flex e-con e-child\" data-id=\"bb0b3e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6550\" class=\"elementor-element elementor-element-9b7782f e-flex e-con-boxed e-con e-child\" data-id=\"9b7782f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b38f980 elementor-widget elementor-widget-text-editor\" data-id=\"b38f980\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les odeurs et les <a href=\"https:\/\/incibeauty.com\/en\/ingredients\/18733-parfum\">parfums<\/a> font partie des rituels de bien-\u00eatre et \u00e9veillent nos sens. Afin que vous puissiez en profiter pleinement, nous pr\u00e9f\u00e9rons nous appuyer sur des ingr\u00e9dients s\u00fbrs. C&rsquo;est pourquoi nous utilisons davantage de fragrances cosm\u00e9tiques que d&rsquo;huiles essentielles, qui pr\u00e9sentent un risque pour les femmes enceintes, les b\u00e9b\u00e9s et les enfants de moins de 6 ans, ainsi que pour les personnes souffrant de troubles hormonaux. Ce sont des ingr\u00e9dients rares et pr\u00e9cieux, c&rsquo;est pourquoi nous pr\u00e9f\u00e9rons les utiliser avec parcimonie, lorsqu&rsquo;ils pr\u00e9sentent un v\u00e9ritable int\u00e9r\u00eat cosm\u00e9tique. Nous utilisons principalement des fragrances d\u00e9velopp\u00e9es et fabriqu\u00e9es par des parfumeurs experts de la c\u00e9l\u00e8bre ville de <a href=\"https:\/\/en.wikipedia.org\/wiki\/Grasse\">Grasse<\/a> en France, ou du Royaume-Uni, r\u00e9put\u00e9s pour leurs fragrances originales et de qualit\u00e9. Nos savons contiennent un maximum de 2 % de fragrance, tandis que nos bougies en contiennent de 8 \u00e0 10 %. Nous n&rsquo;utilisons que des fragrances garanties sans CMR (substances canc\u00e9rig\u00e8nes ou reprotoxiques).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6551\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6551\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Couleurs <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6551\" class=\"elementor-element elementor-element-f18c0ef e-con-full e-flex e-con e-child\" data-id=\"f18c0ef\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6551\" class=\"elementor-element elementor-element-769515d e-flex e-con-boxed e-con e-child\" data-id=\"769515d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0224895 elementor-widget elementor-widget-text-editor\" data-id=\"0224895\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La couleur est un \u00e9l\u00e9ment essentiel de la beaut\u00e9 et de l\u2019expression, sublimant l\u2019exp\u00e9rience esth\u00e9tique des produits du quotidien. Pour vous assurer de pouvoir vous adonner en toute s\u00e9curit\u00e9 \u00e0 cette d\u00e9lectation visuelle, nous nous engageons \u00e0 n&rsquo;utiliser que des colorants naturels. C&rsquo;est pourquoi nous n&#8217;employons exclusivement que des colorants min\u00e9raux (comme l&rsquo;oxyde rouge, l&rsquo;oxyde vert, l&rsquo;oxyde jaune, l&rsquo;oxyde rose, l&rsquo;oxyde violet et le bleu outremer) et des colorants botaniques (incluant les jus de fruits ou de l\u00e9gumes, les poudres, les colorants ou les extraits de plantes) dans nos produits.<\/p>\n<p>Ces colorants sont non seulement visuellement \u00e9poustouflants, mais aussi doux pour la peau et l&rsquo;environnement. Ils sont choisis pour leur puret\u00e9 et leur origine naturelle, garantissant que nos produits sont exempts de colorants synth\u00e9tiques pouvant causer des irritations ou des dommages. En utilisant ces colorants naturels, nous apportons une touche de la palette de la nature \u00e0 nos savons, rehaussant leur beaut\u00e9 sans compromettre la s\u00e9curit\u00e9 ou la durabilit\u00e9.<\/p>\n<p>Notre d\u00e9vouement aux colorants naturels fait partie de notre engagement plus large envers des pratiques \u00e9cologiques et \u00e9thiques. Nous croyons en la cr\u00e9ation de produits qui sont non seulement esth\u00e9tiquement plaisants, mais aussi respectueux \u00e0 la fois de la sant\u00e9 de nos clients et de l&rsquo;environnement.<\/p>\n<p>Avec Hank, vous pouvez profiter des couleurs vibrantes de la nature dans votre vie quotidienne, en sachant avec confiance qu&rsquo;elles sont sourc\u00e9es de mani\u00e8re responsable et avec soin.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6552\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6552\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cire et M\u00e8ches <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6552\" class=\"elementor-element elementor-element-9db0ee5 e-con-full e-flex e-con e-child\" data-id=\"9db0ee5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6552\" class=\"elementor-element elementor-element-00b9cbc e-flex e-con-boxed e-con e-child\" data-id=\"00b9cbc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e433a26 elementor-widget elementor-widget-text-editor\" data-id=\"e433a26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>La cire de colza et de noix de coco<\/strong><\/p>\n<p>La cire de <a href=\"https:\/\/hank.brussels\/fr\/explorez-nos-bougies-poly-2\/\"><span style=\"text-decoration: underline;\">nos bougies<\/span><\/a> t\u00e9moigne de notre engagement en faveur de l&rsquo;\u00e9coresponsabilit\u00e9 et de l&rsquo;approvisionnement \u00e9thique. Le composant noix de coco de notre cire provient de petites exploitations agricoles aux Philippines et en Indon\u00e9sie, garantissant que notre cha\u00eene d&rsquo;approvisionnement soutient les communaut\u00e9s locales sans contribuer \u00e0 la d\u00e9forestation. Cette approche respecte non seulement l&rsquo;environnement, mais favorise \u00e9galement des pratiques agricoles durables.<\/p>\n<p>Le colza utilis\u00e9 dans notre cire est issu de l&rsquo;agriculture europ\u00e9enne, r\u00e9put\u00e9e pour ses normes environnementales \u00e9lev\u00e9es. La culture du colza est principalement r\u00e9alis\u00e9e en rotation, ce qui est une pratique agricole durable cl\u00e9. Cette m\u00e9thode de rotation permet non seulement de restaurer la qualit\u00e9 des sols agricoles, mais joue \u00e9galement un r\u00f4le crucial dans la lutte contre les maladies des cultures c\u00e9r\u00e9ali\u00e8res, ce qui augmente par la suite leurs rendements. De telles pratiques soulignent notre d\u00e9vouement \u00e0 un syst\u00e8me agricole \u00e0 la fois durable et b\u00e9n\u00e9fique pour l&rsquo;\u00e9cosyst\u00e8me.<\/p>\n<p>Notre m\u00e9lange de cire de coco et de colza n&rsquo;est pas seulement \u00e9thique et respectueux de l&rsquo;environnement, mais offre \u00e9galement une qualit\u00e9 de combustion sup\u00e9rieure. Cette combinaison unique permet une dur\u00e9e de combustion plus longue, vous permettant de profiter de l&rsquo;ambiance et du parfum de nos bougies pendant des p\u00e9riodes prolong\u00e9es. L&rsquo;utilisation de ces cires naturelles d&rsquo;origine v\u00e9g\u00e9tale garantit \u00e9galement une combustion plus propre, avec moins de suie et d&rsquo;\u00e9missions nocives par rapport aux cires de paraffine traditionnelles.<\/p>\n<p>En choisissant <a href=\"https:\/\/hank.brussels\/fr\/explorez-nos-bougies-poly-2\/\">les bougies Hank<\/a>, vous ne choisissez pas seulement un produit ; vous prenez la d\u00e9cision consciente de soutenir des pratiques \u00e9cologiques et \u00e9thiques. Notre cire est le symbole de notre engagement ind\u00e9fectible envers la durabilit\u00e9 et la sourcing responsable, garantissant que chaque bougie que nous cr\u00e9ons a un impact positif tant sur l&rsquo;environnement que sur les communaut\u00e9s impliqu\u00e9es dans sa production.<\/p>\n<p><b>M\u00e8ches en Coton &amp; Lin<\/b><\/p>\n<p>Nos m\u00e8ches de bougie en coton et lin sont sp\u00e9cialement con\u00e7ues pour compl\u00e9ter nos bougies \u00e0 base de cire v\u00e9g\u00e9tale. Fabriqu\u00e9es avec un m\u00e9lange de coton non blanchi et de fil de lin, ces m\u00e8ches plates sont con\u00e7ues pour offrir une combustion stable et efficace. Elles excellent dans la r\u00e9duction de la post-combustion et de la fum\u00e9e, am\u00e9liorant la puret\u00e9 et le plaisir de votre exp\u00e9rience de bougie.<\/p>\n<p>La composition naturelle de ces m\u00e8ches s&rsquo;inscrit dans <a href=\"https:\/\/hank.brussels\/fr\/lengagement-ecologique-de-hank\/\">l&rsquo;engagement de Hank<\/a> envers la responsabilit\u00e9 environnementale et la qualit\u00e9. L&rsquo;utilisation de coton non blanchi garantit une combustion plus propre, tandis que le lin ajoute de la force et de la rigidit\u00e9, ce qui est crucial pour une flamme uniforme et constante. Cette s\u00e9lection minutieuse des mat\u00e9riaux garantit que <a href=\"https:\/\/hank.brussels\/fr\/explorez-nos-bougies-poly-2\/\">nos bougies<\/a> br\u00fblent de mani\u00e8re plus propre et fiable, vous offrant une ambiance de chandelle sereine et durable.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-6553\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-6553\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Mat\u00e9riaux <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6553\" class=\"elementor-element elementor-element-ffd5474 e-con-full e-flex e-con e-child\" data-id=\"ffd5474\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-6553\" class=\"elementor-element elementor-element-fe90465 e-flex e-con-boxed e-con e-child\" data-id=\"fe90465\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-538e895 elementor-widget elementor-widget-text-editor\" data-id=\"538e895\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos accessoires pour la maison sont fabriqu\u00e9s \u00e0 partir d\u2019une s\u00e9lection soigneusement choisie de mat\u00e9riaux innovants et de haute qualit\u00e9, s\u00e9lectionn\u00e9s pour leur durabilit\u00e9, leur esth\u00e9tique et leur respect de l\u2019environnement. Nous utilisons des mat\u00e9riaux composites \u00e9cologiques d\u00e9riv\u00e9s de gypse naturel, de plastiques PET recycl\u00e9s et de c\u00e9ramique, tout en \u00e9largissant notre collection pour inclure le verre, le bois, la pierre et d\u2019autres mati\u00e8res naturelles, innovantes ou recycl\u00e9es. <\/p>\n<p>Notre mat\u00e9riau composite \u00e0 base de gypse est un composant innovant \u00e0 base d&rsquo;eau provenant des r\u00e9gions c\u00f4ti\u00e8res d&rsquo;Angleterre. Sans solvants ni compos\u00e9s organiques volatils (COV), il garantit un impact environnemental minimal tout en offrant une r\u00e9sistance exceptionnelle au feu. Son processus de production \u00e9conome en \u00e9nergie ne n\u00e9cessite aucune cuisson et utilise des pigments non toxiques pour la coloration ou l\u2019\u00e9maillage. Plus l\u00e9ger que des mat\u00e9riaux traditionnels comme le ciment ou la pierre, il r\u00e9duit les \u00e9missions li\u00e9es au transport et diminue notre empreinte carbone. De plus, sa polyvalence nous permet de r\u00e9utiliser les r\u00e9sidus de production pour de nouvelles cr\u00e9ations, s&rsquo;inscrivant ainsi parfaitement dans notre philosophie z\u00e9ro d\u00e9chet.    <\/p>\n<p>L\u2019int\u00e9gration du PET recycl\u00e9 apporte une nouvelle dimension \u00e0 notre engagement en faveur de la durabilit\u00e9. En donnant une seconde vie aux d\u00e9chets plastiques, ce mat\u00e9riau permet non seulement de r\u00e9duire les d\u00e9charges, mais offre \u00e9galement une esth\u00e9tique moderne et \u00e9pur\u00e9e. Nos pi\u00e8ces en c\u00e9ramique, qui apparaitront bient\u00f4t dans notre collection, ajoutent une \u00e9l\u00e9gance intemporelle, incarnant les traditions d\u2019un design durable et raffin\u00e9.  <\/p>\n<p>Dans notre d\u00e9marche d\u2019innovation, nous int\u00e9grons de nouveaux mat\u00e9riaux comme le verre, le bois, la pierre et d\u2019autres ressources durables. Qu\u2019ils soient r\u00e9cup\u00e9r\u00e9s, recycl\u00e9s ou issus de sources responsables, ils refl\u00e8tent notre volont\u00e9 de concilier \u00e9l\u00e9gance intemporelle et respect de l\u2019environnement. <\/p>\n<p>Every material we choose tells a story of innovation and respect for the planet, merging tradition with cutting-edge design. Together, they allow us to create home accessories that are not only functional and beautiful but also responsible and forward-thinking. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 propos de Hank \u00c9thique et durabilit\u00e9 Ingr\u00e9dients &amp; Mat\u00e9riaux Nos ingr\u00e9dients Huiles et Beurres Nous utilisons majoritairement des huiles biologiques et \u00e9thiques. Certaines huiles&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2970","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ingr\u00e9dients \u00e9cologiques et mat\u00e9riaux durables dans nos produits<\/title>\n<meta name=\"description\" content=\"Explorez les ingr\u00e9dients de nos savons et bougies, comme les huiles, les beurres... Parfait pour les consommateurs qui appr\u00e9cient les produits respectueux de l&#039;environnement fabriqu\u00e9s avec soin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-video-preview:-1, noimageindex\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos ingr\u00e9dients et mat\u00e9riaux\" \/>\n<meta property=\"og:description\" content=\"Explorez les ingr\u00e9dients de nos savons et bougies, comme les huiles, les beurres... Parfait pour les consommateurs qui appr\u00e9cient les produits respectueux de l&#039;environnement fabriqu\u00e9s avec soin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Hank Brussels\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HankBrssls\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T14:34:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/nos-ingredients-et-materiaux\\\/\",\"url\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/nos-ingredients-et-materiaux\\\/\",\"name\":\"Ingr\u00e9dients \u00e9cologiques et mat\u00e9riaux durables dans nos produits\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#website\"},\"datePublished\":\"2024-03-01T10:07:41+00:00\",\"dateModified\":\"2025-02-25T14:34:41+00:00\",\"description\":\"Explorez les ingr\u00e9dients de nos savons et bougies, comme les huiles, les beurres... Parfait pour les consommateurs qui appr\u00e9cient les produits respectueux de l'environnement fabriqu\u00e9s avec soin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/nos-ingredients-et-materiaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hank.brussels\\\/fr\\\/nos-ingredients-et-materiaux\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/nos-ingredients-et-materiaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos ingr\u00e9dients et mat\u00e9riaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/\",\"name\":\"Hank Brussels\",\"description\":\"Clean Skin. Dirty Mind. Since 2021.\",\"publisher\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#organization\"},\"alternateName\":\"Hank\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#organization\",\"name\":\"Hank Studio SNC\",\"alternateName\":\"Hank\",\"url\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hank.brussels\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Fichier-4.svg\",\"contentUrl\":\"https:\\\/\\\/hank.brussels\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Fichier-4.svg\",\"width\":295,\"height\":295,\"caption\":\"Hank Studio SNC\"},\"image\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HankBrssls\\\/\",\"https:\\\/\\\/www.instagram.com\\\/hank.brussels\\\/\"],\"description\":\"Hank is a creative studio and brand based in Brussels. We offer eco-friendly et thoughtful objects for your everyday life.\",\"email\":\"hello@hank.brussels\",\"telephone\":\"+32 488 24 68 58\",\"legalName\":\"Hank Studio SNC\",\"foundingDate\":\"2021-05-21\",\"vatID\":\"BE0768986306\",\"taxID\":\"0768986306\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ingr\u00e9dients \u00e9cologiques et mat\u00e9riaux durables dans nos produits","description":"Explorez les ingr\u00e9dients de nos savons et bougies, comme les huiles, les beurres... Parfait pour les consommateurs qui appr\u00e9cient les produits respectueux de l'environnement fabriqu\u00e9s avec soin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-video-preview":"max-video-preview:-1","imageindex":"noimageindex"},"canonical":"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos ingr\u00e9dients et mat\u00e9riaux","og_description":"Explorez les ingr\u00e9dients de nos savons et bougies, comme les huiles, les beurres... Parfait pour les consommateurs qui appr\u00e9cient les produits respectueux de l'environnement fabriqu\u00e9s avec soin.","og_url":"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/","og_site_name":"Hank Brussels","article_publisher":"https:\/\/www.facebook.com\/HankBrssls\/","article_modified_time":"2025-02-25T14:34:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/","url":"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/","name":"Ingr\u00e9dients \u00e9cologiques et mat\u00e9riaux durables dans nos produits","isPartOf":{"@id":"https:\/\/hank.brussels\/fr\/#website"},"datePublished":"2024-03-01T10:07:41+00:00","dateModified":"2025-02-25T14:34:41+00:00","description":"Explorez les ingr\u00e9dients de nos savons et bougies, comme les huiles, les beurres... Parfait pour les consommateurs qui appr\u00e9cient les produits respectueux de l'environnement fabriqu\u00e9s avec soin.","breadcrumb":{"@id":"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hank.brussels\/fr\/nos-ingredients-et-materiaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/hank.brussels\/fr\/"},{"@type":"ListItem","position":2,"name":"Nos ingr\u00e9dients et mat\u00e9riaux"}]},{"@type":"WebSite","@id":"https:\/\/hank.brussels\/fr\/#website","url":"https:\/\/hank.brussels\/fr\/","name":"Hank Brussels","description":"Clean Skin. Dirty Mind. Since 2021.","publisher":{"@id":"https:\/\/hank.brussels\/fr\/#organization"},"alternateName":"Hank","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hank.brussels\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hank.brussels\/fr\/#organization","name":"Hank Studio SNC","alternateName":"Hank","url":"https:\/\/hank.brussels\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hank.brussels\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/hank.brussels\/wp-content\/uploads\/2023\/10\/Fichier-4.svg","contentUrl":"https:\/\/hank.brussels\/wp-content\/uploads\/2023\/10\/Fichier-4.svg","width":295,"height":295,"caption":"Hank Studio SNC"},"image":{"@id":"https:\/\/hank.brussels\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HankBrssls\/","https:\/\/www.instagram.com\/hank.brussels\/"],"description":"Hank is a creative studio and brand based in Brussels. We offer eco-friendly et thoughtful objects for your everyday life.","email":"hello@hank.brussels","telephone":"+32 488 24 68 58","legalName":"Hank Studio SNC","foundingDate":"2021-05-21","vatID":"BE0768986306","taxID":"0768986306","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/pages\/2970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/comments?post=2970"}],"version-history":[{"count":0,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/pages\/2970\/revisions"}],"wp:attachment":[{"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/media?parent=2970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}