{"id":3416,"date":"2024-01-23T14:32:20","date_gmt":"2024-01-23T13:32:20","guid":{"rendered":"https:\/\/hank.brussels\/produit\/bandy-porte-savon-et-sous-verre-rouge\/"},"modified":"2025-07-11T16:06:02","modified_gmt":"2025-07-11T15:06:02","slug":"bandy-porte-savon-et-sous-verre-rouge","status":"publish","type":"product","link":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/","title":{"rendered":"Bandy &#8211; Porte-savon et sous-verre, rouge"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3416\" class=\"elementor elementor-3416 elementor-2054\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-424d0ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"424d0ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-21c90a0\" data-id=\"21c90a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13468c8 elementor-widget elementor-widget-heading\" data-id=\"13468c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sp\u00e9cifications<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67a6c5f elementor-widget elementor-widget-etheme_icon_list\" data-id=\"67a6c5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"etheme_icon_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"etheme-icon-list\">\n                                        <div class=\"etheme-icon-list-item elementor-repeater-item-51a7bf7\">\n                                                                \n                                    <span class=\"etheme-icon-list-item-icon\">\n                                        <span class=\"etheme-icon-list-item-icon-inner\">\n                                        .                                        <\/span>\n                                    <\/span>\n                                    \n                                                            \n                            <span class=\"etheme-icon-list-item-text\">\n                                Fabriqu\u00e9 \u00e0 la main en Belgique                            <\/span>\n                                                    <\/div>\n                                            <div class=\"etheme-icon-list-item elementor-repeater-item-f8a6fe5\">\n                                                                \n                                    <span class=\"etheme-icon-list-item-icon\">\n                                        <span class=\"etheme-icon-list-item-icon-inner\">\n                                        .                                        <\/span>\n                                    <\/span>\n                                    \n                                                            \n                            <span class=\"etheme-icon-list-item-text\">\n                                Dimensions - 5 x 5 cm                            <\/span>\n                                                    <\/div>\n                                            <div class=\"etheme-icon-list-item elementor-repeater-item-f3a5a2c\">\n                                                                \n                                    <span class=\"etheme-icon-list-item-icon\">\n                                        <span class=\"etheme-icon-list-item-icon-inner\">\n                                        .                                        <\/span>\n                                    <\/span>\n                                    \n                                                            \n                            <span class=\"etheme-icon-list-item-text\">\n                                Mat\u00e9riau - Jesmonite                            <\/span>\n                                                    <\/div>\n                                <\/div>\n        \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-147ded0\" data-id=\"147ded0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ff0b64 elementor-widget elementor-widget-heading\" data-id=\"7ff0b64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment puis-je nettoyer mon Bandy ?\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed1c5d3 elementor-widget elementor-widget-text-editor\" data-id=\"ed1c5d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Pour un entretien quotidien, utilisez un chiffon sec ou humide tel qu&rsquo;un chamois ou un chiffon en microfibre.<\/p><p>Si des taches sont apparues, lavez \u00e0 l&rsquo;eau et utilisez \u00e9ventuellement un d\u00e9tergent doux. Si les t\u00e2ches sont incrust\u00e9es dans la surface poreuse, humidifiez la zone concern\u00e9e et saupoudrez la tache avec de la terre de sommi\u00e8re, jusqu&rsquo;\u00e0 absorption compl\u00e8te de la tache. Renouvelez l&rsquo;op\u00e9ration si n\u00e9cessaire. Enlever la terre puis nettoyer la surface avec un chiffon. N&rsquo;utilisez pas de vinaigre car il est trop acide pour sa surface de pro.<\/p><p>Utilisez une brosse \u00e0 dents \u00e0 poils doux si n\u00e9cessaire pour les zones plus difficiles, s\u00e9chez, puis traitez la surface avec une huile incolore pour la pierre poreuse ou un produit de traitement d\u00e9di\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bece89 elementor-widget elementor-widget-heading\" data-id=\"7bece89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment puis-je recycler mes articles Hank ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0660ea2 elementor-widget elementor-widget-text-editor\" data-id=\"0660ea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si ceux-ci ne vous plaisent plus, vous pouvez les recycler de la m\u00eame fa\u00e7on que l&rsquo;argile et la c\u00e9ramique, dans votre centre de recyclage local.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rehaussez votre int\u00e9rieur avec le design \u00e9pur\u00e9 de notre porte-savon et dessous de verre Bandy. Cet accessoire \u00e9l\u00e9gant s&rsquo;inspire du serpent bandy-bandy, reproduisant sa fluidit\u00e9 dans une forme qui permet \u00e0 l&rsquo;eau de s&rsquo;\u00e9couler facilement, gardant vos savons secs et durables. En tant que dessous de verre, sa surface textur\u00e9e offre une adh\u00e9rence, \u00e9vitant les glissements et emp\u00eachant l&rsquo;effet de succion caus\u00e9 par l&rsquo;humidit\u00e9. Sa teinte rouge vibrante et son design ludique en font un ajout amusant \u00e0 n&rsquo;importe quelle cuisine ou salle de bain. M\u00e9langez et assortissez pour identifier votre boisson lors de vos soir\u00e9es entre amis. Parfait pour les d\u00e9cors modernes et minimalistes, ce porte-savon et dessous de verre ajoute une touche de charme raffin\u00e9 \u00e0 n&rsquo;importe quel environnement.<\/p>\n","protected":false},"featured_media":1573,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[],"product_brand":[],"product_cat":[259],"product_tag":[],"class_list":["post-3416","product","type-product","status-publish","has-post-thumbnail","product_cat-archive","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bandy - Porte-savon et sous-verre, rouge - Hank Brussels<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bandy - Porte-savon et sous-verre, rouge\" \/>\n<meta property=\"og:description\" content=\"Rehaussez votre int\u00e9rieur avec le design \u00e9pur\u00e9 de notre porte-savon et dessous de verre Bandy. Cet accessoire \u00e9l\u00e9gant s&#039;inspire du serpent bandy-bandy, reproduisant sa fluidit\u00e9 dans une forme qui permet \u00e0 l&#039;eau de s&#039;\u00e9couler facilement, gardant vos savons secs et durables. En tant que dessous de verre, sa surface textur\u00e9e offre une adh\u00e9rence, \u00e9vitant les glissements et emp\u00eachant l&#039;effet de succion caus\u00e9 par l&#039;humidit\u00e9. Sa teinte rouge vibrante et son design ludique en font un ajout amusant \u00e0 n&#039;importe quelle cuisine ou salle de bain. M\u00e9langez et assortissez pour identifier votre boisson lors de vos soir\u00e9es entre amis. Parfait pour les d\u00e9cors modernes et minimalistes, ce porte-savon et dessous de verre ajoute une touche de charme raffin\u00e9 \u00e0 n&#039;importe quel environnement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/\" \/>\n<meta property=\"og:site_name\" content=\"Hank Brussels\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HankBrssls\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T15:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/hank.brussels\/wp-content\/uploads\/2023\/12\/BANDY-RED-920x1200-1.jpg?fit=920%2C1200&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/produit\\\/bandy-porte-savon-et-sous-verre-rouge\\\/\",\"url\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/produit\\\/bandy-porte-savon-et-sous-verre-rouge\\\/\",\"name\":\"Bandy - Porte-savon et sous-verre, rouge - Hank Brussels\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/produit\\\/bandy-porte-savon-et-sous-verre-rouge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/produit\\\/bandy-porte-savon-et-sous-verre-rouge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hank.brussels\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/BANDY-RED-920x1200-1.jpg\",\"datePublished\":\"2024-01-23T13:32:20+00:00\",\"dateModified\":\"2025-07-11T15:06:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/produit\\\/bandy-porte-savon-et-sous-verre-rouge\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hank.brussels\\\/fr\\\/produit\\\/bandy-porte-savon-et-sous-verre-rouge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/produit\\\/bandy-porte-savon-et-sous-verre-rouge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hank.brussels\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/BANDY-RED-920x1200-1.jpg\",\"contentUrl\":\"https:\\\/\\\/hank.brussels\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/BANDY-RED-920x1200-1.jpg\",\"width\":920,\"height\":1200,\"caption\":\"Keep your soap dry or your glass steady with our Bandy soap dish and coaster, inspired by the fluid lines of the bandy-bandy snake.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/produit\\\/bandy-porte-savon-et-sous-verre-rouge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalogue\",\"item\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/catalogue-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bandy &#8211; Porte-savon et sous-verre, rouge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/\",\"name\":\"Hank Brussels\",\"description\":\"Clean Skin. Dirty Mind. Since 2021.\",\"publisher\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#organization\"},\"alternateName\":\"Hank\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#organization\",\"name\":\"Hank Studio SNC\",\"alternateName\":\"Hank\",\"url\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hank.brussels\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Fichier-4.svg\",\"contentUrl\":\"https:\\\/\\\/hank.brussels\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Fichier-4.svg\",\"width\":295,\"height\":295,\"caption\":\"Hank Studio SNC\"},\"image\":{\"@id\":\"https:\\\/\\\/hank.brussels\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HankBrssls\\\/\",\"https:\\\/\\\/www.instagram.com\\\/hank.brussels\\\/\"],\"description\":\"Hank is a creative studio and brand based in Brussels. We offer eco-friendly et thoughtful objects for your everyday life.\",\"email\":\"hello@hank.brussels\",\"telephone\":\"+32 488 24 68 58\",\"legalName\":\"Hank Studio SNC\",\"foundingDate\":\"2021-05-21\",\"vatID\":\"BE0768986306\",\"taxID\":\"0768986306\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bandy - Porte-savon et sous-verre, rouge - Hank Brussels","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/","og_locale":"fr_FR","og_type":"article","og_title":"Bandy - Porte-savon et sous-verre, rouge","og_description":"Rehaussez votre int\u00e9rieur avec le design \u00e9pur\u00e9 de notre porte-savon et dessous de verre Bandy. Cet accessoire \u00e9l\u00e9gant s'inspire du serpent bandy-bandy, reproduisant sa fluidit\u00e9 dans une forme qui permet \u00e0 l'eau de s'\u00e9couler facilement, gardant vos savons secs et durables. En tant que dessous de verre, sa surface textur\u00e9e offre une adh\u00e9rence, \u00e9vitant les glissements et emp\u00eachant l'effet de succion caus\u00e9 par l'humidit\u00e9. Sa teinte rouge vibrante et son design ludique en font un ajout amusant \u00e0 n'importe quelle cuisine ou salle de bain. M\u00e9langez et assortissez pour identifier votre boisson lors de vos soir\u00e9es entre amis. Parfait pour les d\u00e9cors modernes et minimalistes, ce porte-savon et dessous de verre ajoute une touche de charme raffin\u00e9 \u00e0 n'importe quel environnement.","og_url":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/","og_site_name":"Hank Brussels","article_publisher":"https:\/\/www.facebook.com\/HankBrssls\/","article_modified_time":"2025-07-11T15:06:02+00:00","og_image":[{"width":920,"height":1200,"url":"https:\/\/i0.wp.com\/hank.brussels\/wp-content\/uploads\/2023\/12\/BANDY-RED-920x1200-1.jpg?fit=920%2C1200&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/","url":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/","name":"Bandy - Porte-savon et sous-verre, rouge - Hank Brussels","isPartOf":{"@id":"https:\/\/hank.brussels\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/#primaryimage"},"image":{"@id":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/#primaryimage"},"thumbnailUrl":"https:\/\/hank.brussels\/wp-content\/uploads\/2023\/12\/BANDY-RED-920x1200-1.jpg","datePublished":"2024-01-23T13:32:20+00:00","dateModified":"2025-07-11T15:06:02+00:00","breadcrumb":{"@id":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/#primaryimage","url":"https:\/\/hank.brussels\/wp-content\/uploads\/2023\/12\/BANDY-RED-920x1200-1.jpg","contentUrl":"https:\/\/hank.brussels\/wp-content\/uploads\/2023\/12\/BANDY-RED-920x1200-1.jpg","width":920,"height":1200,"caption":"Keep your soap dry or your glass steady with our Bandy soap dish and coaster, inspired by the fluid lines of the bandy-bandy snake."},{"@type":"BreadcrumbList","@id":"https:\/\/hank.brussels\/fr\/produit\/bandy-porte-savon-et-sous-verre-rouge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/hank.brussels\/fr\/"},{"@type":"ListItem","position":2,"name":"Catalogue","item":"https:\/\/hank.brussels\/fr\/catalogue-2\/"},{"@type":"ListItem","position":3,"name":"Bandy &#8211; Porte-savon et sous-verre, rouge"}]},{"@type":"WebSite","@id":"https:\/\/hank.brussels\/fr\/#website","url":"https:\/\/hank.brussels\/fr\/","name":"Hank Brussels","description":"Clean Skin. Dirty Mind. Since 2021.","publisher":{"@id":"https:\/\/hank.brussels\/fr\/#organization"},"alternateName":"Hank","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hank.brussels\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/hank.brussels\/fr\/#organization","name":"Hank Studio SNC","alternateName":"Hank","url":"https:\/\/hank.brussels\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hank.brussels\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/hank.brussels\/wp-content\/uploads\/2023\/10\/Fichier-4.svg","contentUrl":"https:\/\/hank.brussels\/wp-content\/uploads\/2023\/10\/Fichier-4.svg","width":295,"height":295,"caption":"Hank Studio SNC"},"image":{"@id":"https:\/\/hank.brussels\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HankBrssls\/","https:\/\/www.instagram.com\/hank.brussels\/"],"description":"Hank is a creative studio and brand based in Brussels. We offer eco-friendly et thoughtful objects for your everyday life.","email":"hello@hank.brussels","telephone":"+32 488 24 68 58","legalName":"Hank Studio SNC","foundingDate":"2021-05-21","vatID":"BE0768986306","taxID":"0768986306","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/product\/3416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/comments?post=3416"}],"version-history":[{"count":0,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/product\/3416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/media\/1573"}],"wp:attachment":[{"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/media?parent=3416"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/etheme_brands?post=3416"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/product_brand?post=3416"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/product_cat?post=3416"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/hank.brussels\/fr\/wp-json\/wp\/v2\/product_tag?post=3416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}